{"id":2472,"date":"2012-09-01T11:40:24","date_gmt":"2012-09-01T10:40:24","guid":{"rendered":"http:\/\/www.bluetoons.de\/blog\/?p=2472"},"modified":"2018-06-03T20:31:21","modified_gmt":"2018-06-03T19:31:21","slug":"white-crows-herz-aus-stahl","status":"publish","type":"post","link":"https:\/\/www.bluetoons.de\/blog\/2012\/09\/white-crows-herz-aus-stahl\/","title":{"rendered":"White Crows &#8211; Herz aus Stahl"},"content":{"rendered":"<p>Mit White Crows &#8211; Herz aus Stahl ist gerade der Auftakt zu einer dreiteiligen Science-Fiction-Serie erschienen, die ich Euch hier ans Herz legen m&ouml;chte.<\/p>\n<p><strong><img decoding=\"async\" alt=\"White Crows 1 - Herz aus Stahl\" src=\"\/images\/9783868694932.jpg\" style=\"float: left; padding-right: 10px; padding-bottom: 10px; width: 230px; height: 320px;\" \/><\/strong><strong>Autor Djief<\/strong> scheut sich nicht, stereotype Figuren und Handlungselemente zu benutzen. Die Hauptfigur hei&szlig;t Frank Willis, ist ein Muskelprotz, der ein markantes Gesicht hat und mit F&auml;usten und kernigen Spr&uuml;chen seine 15-j&auml;hrige Tochter verteidigt. Dazu kommt der Roboter Vektor, der offenkundig einem gewissen Wall-e nachempfunden wurde. Und die weibliche Hauptfigur erinnert an N&auml;vis aus Sillage.<\/p>\n<p>Trotzdem wei&szlig; Djief im Lauf der Geschichte dann doch zu &uuml;berraschen, z.B. wenn er das Geheimnis der beiden Protagonisten l&uuml;ftet. Das ist mal eine leichte, rasante, mitunter witzige Geschichte, in der nichts wirklich Schlimmes passiert. Sehr unterhaltsam, das Spiel mit den Klischees macht am Ende sogar richtig Spa&szlig;. Gerade weil es dann eben doch abweicht von dem derzeit vorherrschenden Endzeit- \/ Dystopien- \/ Planetenuntergangsmaterial im Science Fiction-Genre. Vieleicht ist es jetzt mal wieder Zeit f&uuml;r sowas.<\/p>\n<p><img decoding=\"async\" alt=\"White Crows - Panel\" src=\"\/images\/white_crows_2.jpg\" style=\"width: 460px; height: 130px;\" \/><\/p>\n<p><strong>Zeichner Djief, <\/strong>der auch schon die bildgewaltige Nibelungenadaption &quot;G&ouml;tterd&auml;mmerung&quot; gezeichnet hat, entwirft den Stadtplaneten Primor, auf dem es von Aliens nur so wimmelt, und auf dem die Menschen die Au&szlig;enseiter sind. Und das sieht schon wunderbar aus. Adolar-Architektur (kleiner interner Begriff, gepr&auml;gt durch die ungarische 70er Jahre Trickfilmserie <a href=\"https:\/\/www.youtube.com\/results?search_query=Adolars+phantastische+Abenteuer&amp;oq=Adolars+phantastische+Abenteuer&amp;gs_l=youtube.3..0l10.1761.6243.0.6521.3.3.0.0.0.0.135.373.0j3.3.0...0.0...1ac.1fTsvK-vYYg\">&quot;Adolars phantastische Abenteuer&quot;<\/a>, f&uuml;r kurvige, flossenf&ouml;rmige, futuristische Bauten :) ), futuristische Inneneinrichtungen und Fortbewegungsmittel. Das ist alles sehr stimmig, da geht alles gut zusammen, das schaue ich mir gerne an. Inklusive toller Dynamik und wirklich sch&ouml;nen Alien-Charakter-Designs.<\/p>\n<p><img decoding=\"async\" alt=\"White Crows 2\" src=\"\/images\/white_crows_1.jpg\" style=\"width: 460px; height: 254px;\" \/><\/p>\n<p>Der Vergleich zu Orbital dr&auml;ngt sich auf, auch hier geht es um die Menschen als Au&szlig;enseiter im Universum, auch hier spielt Rassismus eine Rolle. Allerdings wirkt das Artwork hier viel digitaler. W&auml;hrend man bei Pell&eacute; (Zeicher von Orbital) den Radiergummidreck unter den Fingern&auml;geln zu sp&uuml;ren meint (was ich sehr sch&auml;tze), ist hier alles getrimmt und ge-photoshoped, fast wie in manchen modernen Animes oder wie in Computerspielen. Das hat nat&uuml;rlich eine ganz andere &Auml;sthetik, stilistisch passt das aber auch hier alles sehr gut zusammen, auch was die Farben oder beispielsweise die Dynamik der Actionszenen betrifft. Das Ergebnis ist ein wirklich rundes Album.<\/p>\n<p>Der erste Teil kommt &uuml;brigens zu einem Ende (mal ohne fiesen Cliffhanger), und kann gut f&uuml;r sich gelesen werden. Der 48 seitigen Geschichte folgt noch ein lesenswertes, mehrseitiges bebildertes Dossier &uuml;ber die Welt der White Crows.&nbsp; Auf den zweiten Band freue ich mich schon.<\/p>\n<p>&nbsp;<\/p>\n<p>White Crows 1 &#8211; Herz aus Stahl<br \/>\n\tvon Djief<br \/>\n\tSplitter<br \/>\n\tHardcover, 56 Seiten, farbig, 13.80 EUR<\/p>\n<p>Quelle Abbildungen: <a href=\"http:\/\/www.splitter-verlag.eu\/white-crows-bd-1-herz-aus-stahl.html\">Leseprobe bei Splitter<\/a><br \/>\n\t&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit White Crows &#8211; Herz aus Stahl ist gerade der Auftakt zu einer dreiteiligen Science-Fiction-Serie erschienen, die ich Euch hier ans Herz legen m&ouml;chte. Autor Djief scheut sich nicht, stereotype Figuren und Handlungselemente zu benutzen. Die Hauptfigur hei&szlig;t Frank Willis, ist ein Muskelprotz, der ein markantes Gesicht hat und mit F&auml;usten und kernigen Spr&uuml;chen seine &#8230; <a title=\"White Crows &#8211; Herz aus Stahl\" class=\"read-more\" href=\"https:\/\/www.bluetoons.de\/blog\/2012\/09\/white-crows-herz-aus-stahl\/\" aria-label=\"Mehr dazu unter White Crows &#8211; Herz aus Stahl\">Weiterlesen<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-2472","post","type-post","status-publish","format-standard","hentry","category-science-fiction"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>White Crows - Herz aus Stahl - Comics &amp; Graphics<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bluetoons.de\/blog\/2012\/09\/white-crows-herz-aus-stahl\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"White Crows - Herz aus Stahl - Comics &amp; Graphics\" \/>\n<meta property=\"og:description\" content=\"Mit White Crows &#8211; Herz aus Stahl ist gerade der Auftakt zu einer dreiteiligen Science-Fiction-Serie erschienen, die ich Euch hier ans Herz legen m&ouml;chte. Autor Djief scheut sich nicht, stereotype Figuren und Handlungselemente zu benutzen. Die Hauptfigur hei&szlig;t Frank Willis, ist ein Muskelprotz, der ein markantes Gesicht hat und mit F&auml;usten und kernigen Spr&uuml;chen seine ... Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bluetoons.de\/blog\/2012\/09\/white-crows-herz-aus-stahl\/\" \/>\n<meta property=\"og:site_name\" content=\"Comics &amp; Graphics\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/comicsandgraphics\" \/>\n<meta property=\"article:published_time\" content=\"2012-09-01T10:40:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-03T19:31:21+00:00\" \/>\n<meta name=\"author\" content=\"Frank\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Frank\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.bluetoons.de\/blog\/2012\/09\/white-crows-herz-aus-stahl\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.bluetoons.de\/blog\/2012\/09\/white-crows-herz-aus-stahl\/\"},\"author\":{\"name\":\"Frank\",\"@id\":\"https:\/\/www.bluetoons.de\/blog\/#\/schema\/person\/a6183af3fcd8cb598192c3ba1e71989c\"},\"headline\":\"White Crows &#8211; Herz aus Stahl\",\"datePublished\":\"2012-09-01T10:40:24+00:00\",\"dateModified\":\"2018-06-03T19:31:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.bluetoons.de\/blog\/2012\/09\/white-crows-herz-aus-stahl\/\"},\"wordCount\":465,\"publisher\":{\"@id\":\"https:\/\/www.bluetoons.de\/blog\/#organization\"},\"articleSection\":[\"Science-Fiction\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bluetoons.de\/blog\/2012\/09\/white-crows-herz-aus-stahl\/\",\"url\":\"https:\/\/www.bluetoons.de\/blog\/2012\/09\/white-crows-herz-aus-stahl\/\",\"name\":\"White Crows - Herz aus Stahl - Comics &amp; Graphics\",\"isPartOf\":{\"@id\":\"https:\/\/www.bluetoons.de\/blog\/#website\"},\"datePublished\":\"2012-09-01T10:40:24+00:00\",\"dateModified\":\"2018-06-03T19:31:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bluetoons.de\/blog\/2012\/09\/white-crows-herz-aus-stahl\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bluetoons.de\/blog\/2012\/09\/white-crows-herz-aus-stahl\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bluetoons.de\/blog\/2012\/09\/white-crows-herz-aus-stahl\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.bluetoons.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"White Crows &#8211; Herz aus Stahl\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bluetoons.de\/blog\/#website\",\"url\":\"https:\/\/www.bluetoons.de\/blog\/\",\"name\":\"Comics & Graphics\",\"description\":\"Comicbuchhandlung\",\"publisher\":{\"@id\":\"https:\/\/www.bluetoons.de\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bluetoons.de\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.bluetoons.de\/blog\/#organization\",\"name\":\"Comics & Graphics\",\"url\":\"https:\/\/www.bluetoons.de\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.bluetoons.de\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.bluetoons.de\/blog\/wp-content\/uploads\/cglogo4.png\",\"contentUrl\":\"https:\/\/www.bluetoons.de\/blog\/wp-content\/uploads\/cglogo4.png\",\"width\":457,\"height\":102,\"caption\":\"Comics & Graphics\"},\"image\":{\"@id\":\"https:\/\/www.bluetoons.de\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/comicsandgraphics\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bluetoons.de\/blog\/#\/schema\/person\/a6183af3fcd8cb598192c3ba1e71989c\",\"name\":\"Frank\",\"sameAs\":[\"http:\/\/www.bluetoons.de\"],\"url\":\"https:\/\/www.bluetoons.de\/blog\/author\/fr4nk\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"White Crows - Herz aus Stahl - Comics &amp; Graphics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bluetoons.de\/blog\/2012\/09\/white-crows-herz-aus-stahl\/","og_locale":"de_DE","og_type":"article","og_title":"White Crows - Herz aus Stahl - Comics &amp; Graphics","og_description":"Mit White Crows &#8211; Herz aus Stahl ist gerade der Auftakt zu einer dreiteiligen Science-Fiction-Serie erschienen, die ich Euch hier ans Herz legen m&ouml;chte. Autor Djief scheut sich nicht, stereotype Figuren und Handlungselemente zu benutzen. Die Hauptfigur hei&szlig;t Frank Willis, ist ein Muskelprotz, der ein markantes Gesicht hat und mit F&auml;usten und kernigen Spr&uuml;chen seine ... Weiterlesen","og_url":"https:\/\/www.bluetoons.de\/blog\/2012\/09\/white-crows-herz-aus-stahl\/","og_site_name":"Comics &amp; Graphics","article_publisher":"https:\/\/www.facebook.com\/comicsandgraphics","article_published_time":"2012-09-01T10:40:24+00:00","article_modified_time":"2018-06-03T19:31:21+00:00","author":"Frank","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Frank","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bluetoons.de\/blog\/2012\/09\/white-crows-herz-aus-stahl\/#article","isPartOf":{"@id":"https:\/\/www.bluetoons.de\/blog\/2012\/09\/white-crows-herz-aus-stahl\/"},"author":{"name":"Frank","@id":"https:\/\/www.bluetoons.de\/blog\/#\/schema\/person\/a6183af3fcd8cb598192c3ba1e71989c"},"headline":"White Crows &#8211; Herz aus Stahl","datePublished":"2012-09-01T10:40:24+00:00","dateModified":"2018-06-03T19:31:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bluetoons.de\/blog\/2012\/09\/white-crows-herz-aus-stahl\/"},"wordCount":465,"publisher":{"@id":"https:\/\/www.bluetoons.de\/blog\/#organization"},"articleSection":["Science-Fiction"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.bluetoons.de\/blog\/2012\/09\/white-crows-herz-aus-stahl\/","url":"https:\/\/www.bluetoons.de\/blog\/2012\/09\/white-crows-herz-aus-stahl\/","name":"White Crows - Herz aus Stahl - Comics &amp; Graphics","isPartOf":{"@id":"https:\/\/www.bluetoons.de\/blog\/#website"},"datePublished":"2012-09-01T10:40:24+00:00","dateModified":"2018-06-03T19:31:21+00:00","breadcrumb":{"@id":"https:\/\/www.bluetoons.de\/blog\/2012\/09\/white-crows-herz-aus-stahl\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bluetoons.de\/blog\/2012\/09\/white-crows-herz-aus-stahl\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bluetoons.de\/blog\/2012\/09\/white-crows-herz-aus-stahl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.bluetoons.de\/blog\/"},{"@type":"ListItem","position":2,"name":"White Crows &#8211; Herz aus Stahl"}]},{"@type":"WebSite","@id":"https:\/\/www.bluetoons.de\/blog\/#website","url":"https:\/\/www.bluetoons.de\/blog\/","name":"Comics & Graphics","description":"Comicbuchhandlung","publisher":{"@id":"https:\/\/www.bluetoons.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bluetoons.de\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.bluetoons.de\/blog\/#organization","name":"Comics & Graphics","url":"https:\/\/www.bluetoons.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.bluetoons.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.bluetoons.de\/blog\/wp-content\/uploads\/cglogo4.png","contentUrl":"https:\/\/www.bluetoons.de\/blog\/wp-content\/uploads\/cglogo4.png","width":457,"height":102,"caption":"Comics & Graphics"},"image":{"@id":"https:\/\/www.bluetoons.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/comicsandgraphics"]},{"@type":"Person","@id":"https:\/\/www.bluetoons.de\/blog\/#\/schema\/person\/a6183af3fcd8cb598192c3ba1e71989c","name":"Frank","sameAs":["http:\/\/www.bluetoons.de"],"url":"https:\/\/www.bluetoons.de\/blog\/author\/fr4nk\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bluetoons.de\/blog\/wp-json\/wp\/v2\/posts\/2472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bluetoons.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bluetoons.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bluetoons.de\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bluetoons.de\/blog\/wp-json\/wp\/v2\/comments?post=2472"}],"version-history":[{"count":26,"href":"https:\/\/www.bluetoons.de\/blog\/wp-json\/wp\/v2\/posts\/2472\/revisions"}],"predecessor-version":[{"id":5937,"href":"https:\/\/www.bluetoons.de\/blog\/wp-json\/wp\/v2\/posts\/2472\/revisions\/5937"}],"wp:attachment":[{"href":"https:\/\/www.bluetoons.de\/blog\/wp-json\/wp\/v2\/media?parent=2472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bluetoons.de\/blog\/wp-json\/wp\/v2\/categories?post=2472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bluetoons.de\/blog\/wp-json\/wp\/v2\/tags?post=2472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}