{"id":2542,"date":"2012-11-07T16:57:24","date_gmt":"2012-11-07T15:57:24","guid":{"rendered":"http:\/\/www.bluetoons.de\/blog\/?p=2542"},"modified":"2012-11-07T17:00:28","modified_gmt":"2012-11-07T16:00:28","slug":"interview-gene-luen-yang","status":"publish","type":"post","link":"https:\/\/www.bluetoons.de\/blog\/2012\/11\/interview-gene-luen-yang\/","title":{"rendered":"Interview: Gene Luen Yang"},"content":{"rendered":"<p><img decoding=\"async\" alt=\"Avatar - Band 2\" src=\"\/images\/9783864250668.jpg\" style=\"float: left; padding-right: 10px; padding-bottom: 10px; width: 230px; height: 328px;\" \/>Der zweite Band der Fortsetzung der TV-Serie &quot;Avatar&quot; im Comicformat ist vor einigen Tagen erschienen (Informationen zur Serie siehe auch <a href=\"http:\/\/www.bluetoons.de\/blog\/2012\/09\/avatar-der-herr-der-elemente-das-versprechen\/\">hier im Blog<\/a>). Aus diesem Anlass hier:<\/p>\n<p><strong>Gene Luen Yang &#8211; Kreativer Kopf hinter &quot;Avatar: Der Herr der Elemente &#8211; Das Versprechen&quot; im Interview mit ComicBookresources.com<\/strong><\/p>\n<p><strong>ComicBookresources: <\/strong>Gene, du bist vor allem bekannt f&uuml;r deine eigenst&auml;ndigen Indie-Arbeiten wie &quot;American Born Chinese&quot;. Inwiefern ist &quot;Avatar&quot; Neuland f&uuml;r dich, und wo konntest du deine St&auml;rken einbringen?<\/p>\n<p><strong>Gene Yang:<\/strong> Es ist mein erstes gro&szlig;es Projekt mit Charakteren, die ich nicht geschaffen habe. Ich habe bei &quot;Avatar &#8211; Das Versprechen&quot; daher versucht, den Figuren aus der Originalserie treu zu bleiben. Bevor ich mit dem Schreiben begonnen habe, liefen die &quot;Avatar&quot;-Episoden st&auml;ndig im Hintergrund mit, w&auml;hrend ich an meinen anderen Comics arbeitete. Dieses Projekt war so viel kollaborativer als alle anderen Graphic Novels bisher.<\/p>\n<p>Normalerweise schreibe ich alleine oder zusammen mit engen Freunden. Die Zusammenarbeit mit Mike DiMartino und Bryan Konietzko war eine unglaubliche Erfahrung. Ich konnte von Nahem sehen, wie sie sich durch eine Geschichte arbeiten.<\/p>\n<p>&quot;Avatar &#8211; Das Versprechen&quot; gibt mir die M&ouml;glichkeit, ein wiederkehrendes Thema in meinen anderen B&uuml;chern aufzugreifen: der Zusammensto&szlig; und das Miteinander von Kulturen. Die Serie selbst ist eine Mischung aus &ouml;stlichen und westlichen kulturellen Einfl&uuml;ssen. Es passt also alles zusammen.<\/p>\n<p><strong>CBr:<\/strong> Die Geschichte startet kurz nach der TV-Serie. Gib uns eine kleine Zusammenfassung von dem, was nun kommt. Aber bevor wir in die Details des Buches eintauchen, w&uuml;rde ich gerne deine Gedanken zur Original-Serie h&ouml;ren, und wie du und die Avatar-Erfinder euch die Richtung vorstellt, die Avatar k&uuml;nftig einschlagen wird.<\/p>\n<p><strong>GY:<\/strong> Ja, die Geschichte setzt sofort nach dem Ende der Serie ein, quasi genau einen Moment danach. Ich liebe &#8211; LIEBE &#8211; die Originalserie. Mein guter Freund und Zeichen-Kollege Derek Kirk Kim &uuml;berzeugte mich, es auszuprobieren. Er erz&auml;hlte mir von dieser US-amerikanischen Zeichentrickserie, die sich stark am Anime orientiert &#8211; vor allem Filme von Miyazaki. Er meinte, es w&auml;re die am besten geschriebene US-amerikanische Serie, die er je gesehen hat. Er hatte Recht.<\/p>\n<p>Das Avatar-Universum ist sehr genau konstruiert, mit glaubw&uuml;rdigen Kulturen und Subkulturen. Ebenso wie Miyazakis Figuren sind die Charaktere von &quot;Avatar&quot; fein nuanciert. Jeder gute Charakter hat moralische Schw&auml;chen und jeder b&ouml;se Charakter einen Funken Gutes.<br \/>\n\tDie Comics bilden eine Br&uuml;cke zwischen der Originalserie &quot;Avatar: Der Herr der Elemente&quot; und der kommenden Serie &quot;Die Legende von Korra&quot;. Die Welt von &quot;Korra&quot; hat sich sehr ver&auml;ndert und mit den Comics wollen wir zeigen, wie diese Ver&auml;nderungen zustande gekommen sind.<\/p>\n<p><strong>CBr:<\/strong> Du besch&auml;ftigst dich hier mit einem komplexen Problem, da einige der Kolonialisten seit Generationen in den St&auml;dten des Erdk&ouml;nigreichs leben. Das Echo aus der realen Welt ist hier nicht zu &uuml;bersehen. Wie schwierig ist es, so eine Geschichte f&uuml;r jedes Alter zu vermitteln &#8211; nicht, dass es zu schwierig f&uuml;r Kinder w&auml;re, aber welche Hebel muss man umlegen, damit sowohl Kinder als auch erwachsene von der Geschichte gepackt werden?<\/p>\n<p><strong>GY:<\/strong> Die Original-Serie hat hier gro&szlig;artige Arbeit geleistet. &quot;Avatar: Der Herr der Elemente&quot; war zuerst als Kinderserie beworben.<br \/>\n\tDoch trotzdem ist eine Fangemeinde aus allen Altersstufen zusammen gekommen. Das war nur m&ouml;glich durch die Art, wie Mike, Bryan und ihr Team Geschichten erz&auml;hlen. Die Geschichten waren sehr komplex. Sie besch&auml;ftigten sich mit schwierigen Themen wie Verlust, Familie, Krieg, Kultur und Modernisierung.<\/p>\n<p>Und sie haben es mit Humor, Vorstellungskraft und Anmut umgesetzt. Ich versuche, den gleichen Ton f&uuml;r die Comics zu treffen. Umso besser ich das schaffe, desto wahrscheinlicher wird es, dass Kinder und Erwachsene von den Comics unterhalten werden.<\/p>\n<p><strong>CBr:<\/strong> Wir sehen in der Kolonie Yu Dao, dass die Grenzen zwischen der Feuer- und der Erdnation nicht immer klar zu setzen<br \/>\n\tsind. und auch Aang macht Erfahrungen mit zwiesp&auml;ltigen Allianzen. Erm&ouml;glicht ihm seine besondere Perspektive als Avatar<br \/>\n\tdennoch einen Vorteil, sich in dieser Situation zurecht zu finden?<\/p>\n<p><strong>GY:<\/strong> Wo in der alten Welt die vier Nationen noch getrennt sind, werden sie in der neuen Welt Seite an Seite leben. Wie kommen wir also von hier nach dort? Aang wird nat&uuml;rlich eine entscheidende Rolle spielen, da er der Avatar ist, die Personifikation aller vier Nationen Einem. In &quot;Das Versprechen&quot; wird er lernen, die Welt auf eine neue Weise zu sehen, einen modernen Blick entwickeln.<\/p>\n<p><strong>CBr:<\/strong> Du arbeitest mit dem Gurihiru Studio an diesem Buch. Was macht sie so passend f&uuml;r &quot;Avatar&quot;?<\/p>\n<p><strong>GY:<\/strong> Hast du ihre Arbeit in &quot;Avatar &#8211; Das Versprechen&quot; gesehen? Sie ist fantastisch! Sie bleibt der TV-Geschichte treu, nutzt aber auch alle Vorteile des Mediums Comic. Die Gesichtsausdr&uuml;cke, die Kulissen, die Anordnung der Panels &#8211; alles ist genau ins Schwarze getroffen. Und genau wie die TV-Serie mischen Gurihiru &ouml;stliche und westliche Einfl&uuml;sse zusammen. Ehrlich, ihre Sachen sind erschreckend gut.<\/p>\n<p><strong>CBr:<\/strong> Gibt es noch irgendetwas, das du uns &uuml;ber &quot;Avatar &#8211; Das Versprechen&quot; mitteilen m&ouml;chtest?<\/p>\n<p><strong>GY:<\/strong> Dieses Projekt hat einen Wahnsinnsspa&szlig; gemacht! Die Leute von Dark Horse und Nickelodeon waren wundervolle Arbeitskollegen. Und ich hoffe, ein Teil dieser Freude spiegelt sich auch auf den Seiten wieder!<\/p>\n<p><strong><img decoding=\"async\" alt=\"\" src=\"\/images\/avatar-sketch.jpg\" style=\"width: 460px; height: 162px;\" \/><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>GENE LUEN YANG<\/strong><\/p>\n<p><strong><img decoding=\"async\" alt=\"Gene Luen Yang\" src=\"\/images\/avatar-yang.jpg\" style=\"float: left; padding-right: 10px; padding-bottom: 10px; width: 115px; height: 197px;\" \/><\/strong>Yang startete 1996 unter seinem eigenem Label &quot;Humble Comics&quot; mit Yamamoto and the King of the Geeks, wof&uuml;r er sp&auml;ter den Xeric&nbsp; Grant erhielt. Seither schrieb und zeichnete er zahlreiche Comics bei First Second Books. Mit seiner Arbeit American Born Chinese konnte er 2006 Fans und Kritiker &uuml;berzeugen und erhielt den American Library Association&#39;s Printz Award sowie einen Eisner Award f&uuml;r Best Graphic Album &#8211; New. Das kollaborative Projekt &quot;The Eternal Smile&quot; zusammen mit Derek Kirk Kim von 2009 und die 2010 erschienene Graphic Novel &quot;Prime Baby&quot; wurden ebenfalls mit dem Eisner Award ausgezeichnet. Seit 2012 arbeitet Yang zusammen mit den Avatar-Erfindern Mike DiMartino und Bryan Konietzko und dem K&uuml;nstlerstudio Gurihiru an der Fortsetzungsreihe &quot;Avatar: Der Herr der Elemente &#8211; Das Versprechen&quot;. Eine weitere Avatar-Reihe &quot;Avatar: Der Herr der Elemente &#8211; Die Suche&quot; ist bereits in Planung.<\/p>\n<p>Neben seiner T&auml;tigkeit als Autor und Zeichner unterrichtet Yang Computer Science an einer High School und als Dozent an der Hamline University in Saint Paul, Minnesota.<\/p>\n<p><strong>GURIHIRU<\/strong><\/p>\n<p>Die K&uuml;nstlerinnen Sasaki und Kawano aus Saitama, Japan, arbeiten unter dem Studionamen Gurihiru &uuml;berwiegend als Zeichnerinnen f&uuml;r US-amerikanische Ver&ouml;ffentlichungen. Zeichnung und Konturen stammen von Sasaki, die Koloration &uuml;bernimmt Kawano. Nebenbei besch&auml;ftigt sich das Duo auch mit Illustrationen und Charakterdesigns f&uuml;r japanische Games und Animationsfilme.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size:9px;\">Quelle: Presseinfo Crosscult<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der zweite Band der Fortsetzung der TV-Serie &quot;Avatar&quot; im Comicformat ist vor einigen Tagen erschienen (Informationen zur Serie siehe auch hier im Blog). Aus diesem Anlass hier: Gene Luen Yang &#8211; Kreativer Kopf hinter &quot;Avatar: Der Herr der Elemente &#8211; Das Versprechen&quot; im Interview mit ComicBookresources.com ComicBookresources: Gene, du bist vor allem bekannt f&uuml;r deine &#8230; <a title=\"Interview: Gene Luen Yang\" class=\"read-more\" href=\"https:\/\/www.bluetoons.de\/blog\/2012\/11\/interview-gene-luen-yang\/\" aria-label=\"Mehr dazu unter Interview: Gene Luen Yang\">Weiterlesen<\/a><\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,25,81],"tags":[],"class_list":["post-2542","post","type-post","status-publish","format-standard","hentry","category-fantasy","category-interviews","category-kino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Interview: Gene Luen Yang - Comics &amp; Graphics<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bluetoons.de\/blog\/2012\/11\/interview-gene-luen-yang\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interview: Gene Luen Yang - Comics &amp; Graphics\" \/>\n<meta property=\"og:description\" content=\"Der zweite Band der Fortsetzung der TV-Serie &quot;Avatar&quot; im Comicformat ist vor einigen Tagen erschienen (Informationen zur Serie siehe auch hier im Blog). Aus diesem Anlass hier: Gene Luen Yang &#8211; Kreativer Kopf hinter &quot;Avatar: Der Herr der Elemente &#8211; Das Versprechen&quot; im Interview mit ComicBookresources.com ComicBookresources: Gene, du bist vor allem bekannt f&uuml;r deine ... Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bluetoons.de\/blog\/2012\/11\/interview-gene-luen-yang\/\" \/>\n<meta property=\"og:site_name\" content=\"Comics &amp; Graphics\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/comicsandgraphics\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-07T15:57:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-11-07T16:00:28+00:00\" \/>\n<meta name=\"author\" content=\"urtier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"urtier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.bluetoons.de\/blog\/2012\/11\/interview-gene-luen-yang\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.bluetoons.de\/blog\/2012\/11\/interview-gene-luen-yang\/\"},\"author\":{\"name\":\"urtier\",\"@id\":\"https:\/\/www.bluetoons.de\/blog\/#\/schema\/person\/5b84603ef3c1e8801bf69622f3bc8b15\"},\"headline\":\"Interview: Gene Luen Yang\",\"datePublished\":\"2012-11-07T15:57:24+00:00\",\"dateModified\":\"2012-11-07T16:00:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.bluetoons.de\/blog\/2012\/11\/interview-gene-luen-yang\/\"},\"wordCount\":1187,\"publisher\":{\"@id\":\"https:\/\/www.bluetoons.de\/blog\/#organization\"},\"articleSection\":[\"Fantasy\",\"Interviews\",\"Kino\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bluetoons.de\/blog\/2012\/11\/interview-gene-luen-yang\/\",\"url\":\"https:\/\/www.bluetoons.de\/blog\/2012\/11\/interview-gene-luen-yang\/\",\"name\":\"Interview: Gene Luen Yang - Comics &amp; Graphics\",\"isPartOf\":{\"@id\":\"https:\/\/www.bluetoons.de\/blog\/#website\"},\"datePublished\":\"2012-11-07T15:57:24+00:00\",\"dateModified\":\"2012-11-07T16:00:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bluetoons.de\/blog\/2012\/11\/interview-gene-luen-yang\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bluetoons.de\/blog\/2012\/11\/interview-gene-luen-yang\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bluetoons.de\/blog\/2012\/11\/interview-gene-luen-yang\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.bluetoons.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interview: Gene Luen Yang\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bluetoons.de\/blog\/#website\",\"url\":\"https:\/\/www.bluetoons.de\/blog\/\",\"name\":\"Comics & Graphics\",\"description\":\"Comicbuchhandlung\",\"publisher\":{\"@id\":\"https:\/\/www.bluetoons.de\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bluetoons.de\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.bluetoons.de\/blog\/#organization\",\"name\":\"Comics & Graphics\",\"url\":\"https:\/\/www.bluetoons.de\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.bluetoons.de\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.bluetoons.de\/blog\/wp-content\/uploads\/cglogo4.png\",\"contentUrl\":\"https:\/\/www.bluetoons.de\/blog\/wp-content\/uploads\/cglogo4.png\",\"width\":457,\"height\":102,\"caption\":\"Comics & Graphics\"},\"image\":{\"@id\":\"https:\/\/www.bluetoons.de\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/comicsandgraphics\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bluetoons.de\/blog\/#\/schema\/person\/5b84603ef3c1e8801bf69622f3bc8b15\",\"name\":\"urtier\",\"url\":\"https:\/\/www.bluetoons.de\/blog\/author\/urtier\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interview: Gene Luen Yang - Comics &amp; Graphics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bluetoons.de\/blog\/2012\/11\/interview-gene-luen-yang\/","og_locale":"de_DE","og_type":"article","og_title":"Interview: Gene Luen Yang - Comics &amp; Graphics","og_description":"Der zweite Band der Fortsetzung der TV-Serie &quot;Avatar&quot; im Comicformat ist vor einigen Tagen erschienen (Informationen zur Serie siehe auch hier im Blog). Aus diesem Anlass hier: Gene Luen Yang &#8211; Kreativer Kopf hinter &quot;Avatar: Der Herr der Elemente &#8211; Das Versprechen&quot; im Interview mit ComicBookresources.com ComicBookresources: Gene, du bist vor allem bekannt f&uuml;r deine ... Weiterlesen","og_url":"https:\/\/www.bluetoons.de\/blog\/2012\/11\/interview-gene-luen-yang\/","og_site_name":"Comics &amp; Graphics","article_publisher":"https:\/\/www.facebook.com\/comicsandgraphics","article_published_time":"2012-11-07T15:57:24+00:00","article_modified_time":"2012-11-07T16:00:28+00:00","author":"urtier","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"urtier","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bluetoons.de\/blog\/2012\/11\/interview-gene-luen-yang\/#article","isPartOf":{"@id":"https:\/\/www.bluetoons.de\/blog\/2012\/11\/interview-gene-luen-yang\/"},"author":{"name":"urtier","@id":"https:\/\/www.bluetoons.de\/blog\/#\/schema\/person\/5b84603ef3c1e8801bf69622f3bc8b15"},"headline":"Interview: Gene Luen Yang","datePublished":"2012-11-07T15:57:24+00:00","dateModified":"2012-11-07T16:00:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bluetoons.de\/blog\/2012\/11\/interview-gene-luen-yang\/"},"wordCount":1187,"publisher":{"@id":"https:\/\/www.bluetoons.de\/blog\/#organization"},"articleSection":["Fantasy","Interviews","Kino"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.bluetoons.de\/blog\/2012\/11\/interview-gene-luen-yang\/","url":"https:\/\/www.bluetoons.de\/blog\/2012\/11\/interview-gene-luen-yang\/","name":"Interview: Gene Luen Yang - Comics &amp; Graphics","isPartOf":{"@id":"https:\/\/www.bluetoons.de\/blog\/#website"},"datePublished":"2012-11-07T15:57:24+00:00","dateModified":"2012-11-07T16:00:28+00:00","breadcrumb":{"@id":"https:\/\/www.bluetoons.de\/blog\/2012\/11\/interview-gene-luen-yang\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bluetoons.de\/blog\/2012\/11\/interview-gene-luen-yang\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bluetoons.de\/blog\/2012\/11\/interview-gene-luen-yang\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.bluetoons.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Interview: Gene Luen Yang"}]},{"@type":"WebSite","@id":"https:\/\/www.bluetoons.de\/blog\/#website","url":"https:\/\/www.bluetoons.de\/blog\/","name":"Comics & Graphics","description":"Comicbuchhandlung","publisher":{"@id":"https:\/\/www.bluetoons.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bluetoons.de\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.bluetoons.de\/blog\/#organization","name":"Comics & Graphics","url":"https:\/\/www.bluetoons.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.bluetoons.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.bluetoons.de\/blog\/wp-content\/uploads\/cglogo4.png","contentUrl":"https:\/\/www.bluetoons.de\/blog\/wp-content\/uploads\/cglogo4.png","width":457,"height":102,"caption":"Comics & Graphics"},"image":{"@id":"https:\/\/www.bluetoons.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/comicsandgraphics"]},{"@type":"Person","@id":"https:\/\/www.bluetoons.de\/blog\/#\/schema\/person\/5b84603ef3c1e8801bf69622f3bc8b15","name":"urtier","url":"https:\/\/www.bluetoons.de\/blog\/author\/urtier\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bluetoons.de\/blog\/wp-json\/wp\/v2\/posts\/2542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bluetoons.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bluetoons.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bluetoons.de\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bluetoons.de\/blog\/wp-json\/wp\/v2\/comments?post=2542"}],"version-history":[{"count":8,"href":"https:\/\/www.bluetoons.de\/blog\/wp-json\/wp\/v2\/posts\/2542\/revisions"}],"predecessor-version":[{"id":2669,"href":"https:\/\/www.bluetoons.de\/blog\/wp-json\/wp\/v2\/posts\/2542\/revisions\/2669"}],"wp:attachment":[{"href":"https:\/\/www.bluetoons.de\/blog\/wp-json\/wp\/v2\/media?parent=2542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bluetoons.de\/blog\/wp-json\/wp\/v2\/categories?post=2542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bluetoons.de\/blog\/wp-json\/wp\/v2\/tags?post=2542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}